{"id":1237,"date":"2015-08-17T16:08:45","date_gmt":"2015-08-17T13:08:45","guid":{"rendered":"http:\/\/tantsugeen.ee\/treenerid\/?lang=en"},"modified":"2016-04-05T16:36:12","modified_gmt":"2016-04-05T13:36:12","slug":"treenerid","status":"publish","type":"page","link":"https:\/\/www.tantsugeen.ee\/en\/treenerid\/","title":{"rendered":"Trainer"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"custom-templates\/trainers.php","meta":{"footnotes":""},"class_list":["post-1237","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Trainer | Tantsugeen<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/tantsugeen.ee\/en\/treenerid\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Trainer | Tantsugeen\" \/>\n<meta property=\"og:url\" content=\"https:\/\/tantsugeen.ee\/en\/treenerid\/\" \/>\n<meta property=\"og:site_name\" content=\"Tantsugeen\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/TantsuGeen\" \/>\n<meta property=\"article:modified_time\" content=\"2016-04-05T13:36:12+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/tantsugeen.ee\/static\/taustapilt2.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/tantsugeen.ee\/en\/treenerid\/\",\"url\":\"https:\/\/tantsugeen.ee\/en\/treenerid\/\",\"name\":\"Trainer | Tantsugeen\",\"isPartOf\":{\"@id\":\"https:\/\/tantsugeen.ee\/#website\"},\"datePublished\":\"2015-08-17T13:08:45+00:00\",\"dateModified\":\"2016-04-05T13:36:12+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/tantsugeen.ee\/en\/treenerid\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/tantsugeen.ee\/en\/treenerid\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/tantsugeen.ee\/en\/treenerid\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.tantsugeen.ee\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Trainer\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/tantsugeen.ee\/#website\",\"url\":\"https:\/\/tantsugeen.ee\/\",\"name\":\"Tantsugeen\",\"description\":\"J&auml;rjekordne WordPressi veebileht\",\"publisher\":{\"@id\":\"https:\/\/tantsugeen.ee\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/tantsugeen.ee\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/tantsugeen.ee\/#organization\",\"name\":\"Tantsugeen\",\"url\":\"https:\/\/tantsugeen.ee\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/tantsugeen.ee\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.tantsugeen.ee\/static\/731F669D-BF4E-463C-88CF-9DDFA896BC0D-scaled.jpeg\",\"contentUrl\":\"https:\/\/www.tantsugeen.ee\/static\/731F669D-BF4E-463C-88CF-9DDFA896BC0D-scaled.jpeg\",\"width\":2048,\"height\":2560,\"caption\":\"Tantsugeen\"},\"image\":{\"@id\":\"https:\/\/tantsugeen.ee\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/TantsuGeen\",\"https:\/\/www.instagram.com\/tantsugeen\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Trainer | Tantsugeen","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/tantsugeen.ee\/en\/treenerid\/","og_locale":"en_US","og_type":"article","og_title":"Trainer | Tantsugeen","og_url":"https:\/\/tantsugeen.ee\/en\/treenerid\/","og_site_name":"Tantsugeen","article_publisher":"https:\/\/www.facebook.com\/TantsuGeen","article_modified_time":"2016-04-05T13:36:12+00:00","og_image":[{"url":"http:\/\/tantsugeen.ee\/static\/taustapilt2.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/tantsugeen.ee\/en\/treenerid\/","url":"https:\/\/tantsugeen.ee\/en\/treenerid\/","name":"Trainer | Tantsugeen","isPartOf":{"@id":"https:\/\/tantsugeen.ee\/#website"},"datePublished":"2015-08-17T13:08:45+00:00","dateModified":"2016-04-05T13:36:12+00:00","breadcrumb":{"@id":"https:\/\/tantsugeen.ee\/en\/treenerid\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/tantsugeen.ee\/en\/treenerid\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/tantsugeen.ee\/en\/treenerid\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.tantsugeen.ee\/en\/"},{"@type":"ListItem","position":2,"name":"Trainer"}]},{"@type":"WebSite","@id":"https:\/\/tantsugeen.ee\/#website","url":"https:\/\/tantsugeen.ee\/","name":"Tantsugeen","description":"J&auml;rjekordne WordPressi veebileht","publisher":{"@id":"https:\/\/tantsugeen.ee\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/tantsugeen.ee\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/tantsugeen.ee\/#organization","name":"Tantsugeen","url":"https:\/\/tantsugeen.ee\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/tantsugeen.ee\/#\/schema\/logo\/image\/","url":"https:\/\/www.tantsugeen.ee\/static\/731F669D-BF4E-463C-88CF-9DDFA896BC0D-scaled.jpeg","contentUrl":"https:\/\/www.tantsugeen.ee\/static\/731F669D-BF4E-463C-88CF-9DDFA896BC0D-scaled.jpeg","width":2048,"height":2560,"caption":"Tantsugeen"},"image":{"@id":"https:\/\/tantsugeen.ee\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/TantsuGeen","https:\/\/www.instagram.com\/tantsugeen"]}]}},"_links":{"self":[{"href":"https:\/\/www.tantsugeen.ee\/en\/wp-json\/wp\/v2\/pages\/1237","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tantsugeen.ee\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.tantsugeen.ee\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.tantsugeen.ee\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tantsugeen.ee\/en\/wp-json\/wp\/v2\/comments?post=1237"}],"version-history":[{"count":0,"href":"https:\/\/www.tantsugeen.ee\/en\/wp-json\/wp\/v2\/pages\/1237\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.tantsugeen.ee\/en\/wp-json\/wp\/v2\/media?parent=1237"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}