{"id":7089,"date":"2026-01-01T18:29:59","date_gmt":"2026-01-01T16:29:59","guid":{"rendered":"https:\/\/www.tantsugeen.ee\/static\/Untitled-design-10.png"},"modified":"2026-01-01T18:29:59","modified_gmt":"2026-01-01T16:29:59","slug":"untitled-design-10-2","status":"inherit","type":"attachment","link":"https:\/\/www.tantsugeen.ee\/ru\/kontakt\/untitled-design-10-2\/","title":{"rendered":"Untitled design (10)"},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"class_list":["post-7089","attachment","type-attachment","status-inherit","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Untitled design (10) | Tantsugeen<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/tantsugeen.ee\/static\/Untitled-design-10.png\" \/>\n<meta property=\"og:locale\" content=\"ru_RU\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Untitled design (10) | Tantsugeen\" \/>\n<meta property=\"og:url\" content=\"https:\/\/tantsugeen.ee\/static\/Untitled-design-10.png\" \/>\n<meta property=\"og:site_name\" content=\"Tantsugeen\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/TantsuGeen\" \/>\n<meta property=\"og:image\" content=\"https:\/\/tantsugeen.ee\/static\/Untitled-design-10.png\" \/>\n\t<meta property=\"og:image:width\" content=\"2000\" \/>\n\t<meta property=\"og:image:height\" content=\"611\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/tantsugeen.ee\/static\/Untitled-design-10.png\",\"url\":\"https:\/\/tantsugeen.ee\/static\/Untitled-design-10.png\",\"name\":\"Untitled design (10) | Tantsugeen\",\"isPartOf\":{\"@id\":\"https:\/\/tantsugeen.ee\/#website\"},\"datePublished\":\"2026-01-01T16:29:59+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/tantsugeen.ee\/static\/Untitled-design-10.png#breadcrumb\"},\"inLanguage\":\"ru-RU\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/tantsugeen.ee\/static\/Untitled-design-10.png\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/tantsugeen.ee\/static\/Untitled-design-10.png#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.tantsugeen.ee\/ru\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u041a\u041e\u041d\u0422\u0410\u041a\u0422\",\"item\":\"https:\/\/www.tantsugeen.ee\/ru\/kontakt\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Untitled design (10)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/tantsugeen.ee\/#website\",\"url\":\"https:\/\/tantsugeen.ee\/\",\"name\":\"Tantsugeen\",\"description\":\"J&auml;rjekordne WordPressi veebileht\",\"publisher\":{\"@id\":\"https:\/\/tantsugeen.ee\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/tantsugeen.ee\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ru-RU\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/tantsugeen.ee\/#organization\",\"name\":\"Tantsugeen\",\"url\":\"https:\/\/tantsugeen.ee\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ru-RU\",\"@id\":\"https:\/\/tantsugeen.ee\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.tantsugeen.ee\/static\/731F669D-BF4E-463C-88CF-9DDFA896BC0D-scaled.jpeg\",\"contentUrl\":\"https:\/\/www.tantsugeen.ee\/static\/731F669D-BF4E-463C-88CF-9DDFA896BC0D-scaled.jpeg\",\"width\":2048,\"height\":2560,\"caption\":\"Tantsugeen\"},\"image\":{\"@id\":\"https:\/\/tantsugeen.ee\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/TantsuGeen\",\"https:\/\/www.instagram.com\/tantsugeen\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Untitled design (10) | Tantsugeen","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/tantsugeen.ee\/static\/Untitled-design-10.png","og_locale":"ru_RU","og_type":"article","og_title":"Untitled design (10) | Tantsugeen","og_url":"https:\/\/tantsugeen.ee\/static\/Untitled-design-10.png","og_site_name":"Tantsugeen","article_publisher":"https:\/\/www.facebook.com\/TantsuGeen","og_image":[{"width":2000,"height":611,"url":"https:\/\/tantsugeen.ee\/static\/Untitled-design-10.png","type":"image\/png"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/tantsugeen.ee\/static\/Untitled-design-10.png","url":"https:\/\/tantsugeen.ee\/static\/Untitled-design-10.png","name":"Untitled design (10) | Tantsugeen","isPartOf":{"@id":"https:\/\/tantsugeen.ee\/#website"},"datePublished":"2026-01-01T16:29:59+00:00","breadcrumb":{"@id":"https:\/\/tantsugeen.ee\/static\/Untitled-design-10.png#breadcrumb"},"inLanguage":"ru-RU","potentialAction":[{"@type":"ReadAction","target":["https:\/\/tantsugeen.ee\/static\/Untitled-design-10.png"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/tantsugeen.ee\/static\/Untitled-design-10.png#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.tantsugeen.ee\/ru\/"},{"@type":"ListItem","position":2,"name":"\u041a\u041e\u041d\u0422\u0410\u041a\u0422","item":"https:\/\/www.tantsugeen.ee\/ru\/kontakt\/"},{"@type":"ListItem","position":3,"name":"Untitled design (10)"}]},{"@type":"WebSite","@id":"https:\/\/tantsugeen.ee\/#website","url":"https:\/\/tantsugeen.ee\/","name":"Tantsugeen","description":"J&auml;rjekordne WordPressi veebileht","publisher":{"@id":"https:\/\/tantsugeen.ee\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/tantsugeen.ee\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ru-RU"},{"@type":"Organization","@id":"https:\/\/tantsugeen.ee\/#organization","name":"Tantsugeen","url":"https:\/\/tantsugeen.ee\/","logo":{"@type":"ImageObject","inLanguage":"ru-RU","@id":"https:\/\/tantsugeen.ee\/#\/schema\/logo\/image\/","url":"https:\/\/www.tantsugeen.ee\/static\/731F669D-BF4E-463C-88CF-9DDFA896BC0D-scaled.jpeg","contentUrl":"https:\/\/www.tantsugeen.ee\/static\/731F669D-BF4E-463C-88CF-9DDFA896BC0D-scaled.jpeg","width":2048,"height":2560,"caption":"Tantsugeen"},"image":{"@id":"https:\/\/tantsugeen.ee\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/TantsuGeen","https:\/\/www.instagram.com\/tantsugeen"]}]}},"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/www.tantsugeen.ee\/static\/Untitled-design-10.png'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"92\" src=\"https:\/\/www.tantsugeen.ee\/static\/Untitled-design-10-300x92.png\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.tantsugeen.ee\/static\/Untitled-design-10-300x92.png 300w, https:\/\/www.tantsugeen.ee\/static\/Untitled-design-10-1024x313.png 1024w, https:\/\/www.tantsugeen.ee\/static\/Untitled-design-10-768x235.png 768w, https:\/\/www.tantsugeen.ee\/static\/Untitled-design-10-1536x469.png 1536w, https:\/\/www.tantsugeen.ee\/static\/Untitled-design-10-460x141.png 460w, https:\/\/www.tantsugeen.ee\/static\/Untitled-design-10.png 2000w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/png","media_details":{"width":2000,"height":611,"file":"Untitled-design-10.png","filesize":351974,"sizes":{"medium":{"file":"Untitled-design-10-300x92.png","width":300,"height":92,"filesize":19808,"mime_type":"image\/png","source_url":"https:\/\/www.tantsugeen.ee\/static\/Untitled-design-10-300x92.png"},"large":{"file":"Untitled-design-10-1024x313.png","width":1024,"height":313,"filesize":113804,"mime_type":"image\/png","source_url":"https:\/\/www.tantsugeen.ee\/static\/Untitled-design-10-1024x313.png"},"thumbnail":{"file":"Untitled-design-10-150x150.png","width":150,"height":150,"filesize":13987,"mime_type":"image\/png","source_url":"https:\/\/www.tantsugeen.ee\/static\/Untitled-design-10-150x150.png"},"medium_large":{"file":"Untitled-design-10-768x235.png","width":768,"height":235,"filesize":75033,"mime_type":"image\/png","source_url":"https:\/\/www.tantsugeen.ee\/static\/Untitled-design-10-768x235.png"},"1536x1536":{"file":"Untitled-design-10-1536x469.png","width":1536,"height":469,"filesize":208947,"mime_type":"image\/png","source_url":"https:\/\/www.tantsugeen.ee\/static\/Untitled-design-10-1536x469.png"},"trainings_img":{"file":"Untitled-design-10-999x230.png","width":999,"height":230,"filesize":108360,"mime_type":"image\/png","source_url":"https:\/\/www.tantsugeen.ee\/static\/Untitled-design-10-999x230.png"},"trainer_small_img":{"file":"Untitled-design-10-250x160.png","width":250,"height":160,"filesize":23824,"mime_type":"image\/png","source_url":"https:\/\/www.tantsugeen.ee\/static\/Untitled-design-10-250x160.png"},"trainer_big_img":{"file":"Untitled-design-10-460x141.png","width":460,"height":141,"filesize":36209,"mime_type":"image\/png","source_url":"https:\/\/www.tantsugeen.ee\/static\/Untitled-design-10-460x141.png"},"full":{"file":"Untitled-design-10.png","width":2000,"height":611,"mime_type":"image\/png","source_url":"https:\/\/www.tantsugeen.ee\/static\/Untitled-design-10.png"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":1224,"source_url":"https:\/\/www.tantsugeen.ee\/static\/Untitled-design-10.png","_links":{"self":[{"href":"https:\/\/www.tantsugeen.ee\/ru\/wp-json\/wp\/v2\/media\/7089","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tantsugeen.ee\/ru\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/www.tantsugeen.ee\/ru\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/www.tantsugeen.ee\/ru\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tantsugeen.ee\/ru\/wp-json\/wp\/v2\/comments?post=7089"}],"wp:attached-to":[{"embeddable":true,"post_type":"page","id":1224,"href":"https:\/\/www.tantsugeen.ee\/ru\/wp-json\/wp\/v2\/pages\/1224"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}